{"id":9077,"date":"2026-06-30T15:24:49","date_gmt":"2026-06-30T15:24:49","guid":{"rendered":"https:\/\/onurbegrup.com\/propiedad\/traspaso-de-centro-de-bienestar-junto-a-la-sagrada-familia\/"},"modified":"2026-06-30T15:24:49","modified_gmt":"2026-06-30T15:24:49","slug":"traspaso-de-centro-de-bienestar-junto-a-la-sagrada-familia","status":"publish","type":"propiedad","link":"https:\/\/onurbegrup.com\/es\/propiedad\/traspaso-de-centro-de-bienestar-junto-a-la-sagrada-familia\/","title":{"rendered":"Traspaso de centro de bienestar junto a la Sagrada Familia"},"content":{"rendered":"<p>Traspaso de centro de masajes\/spa-peluquer\u00eda-venta de productos completamente reformada y equipada lista para continuar con la actividad en barrio Sagrada Familia! El local cuenta con 90 m\u00b2 completamente reformado, el espacio cuenta con equipaciones de alta calidad, incluyendo jacuzzi, camillas profesionales, ducha y todo lo necesario para desarrollar el negocio sin necesidad de inversi\u00f3n adicional. Ubicado a tan solo una calles de la Sagrada Familia, en una zona con tr\u00e1nsito peatonal continuo de residentes y turistas que pasan hacia esta importante atracci\u00f3n, el negocio ofrece un gran potencial para captar una clientela constante y variada. La excelente ubicaci\u00f3n, combinada con el dise\u00f1o impecable y el equipamiento, convierten este local en una inversi\u00f3n perfecta para quien quiera iniciar o ampliar un negocio en un \u00e1rea con alta demanda. Cont\u00e1ctanos para organizar una visita y conocer este espacio lleno de posibilidades<\/p>\n","protected":false},"featured_media":9078,"template":"","meta":{"_acf_changed":false,"_joinchat":[]},"operacion":[147],"poblacion":[156],"subzona":[],"tipo-de-inmueble":[168],"zona":[],"class_list":["post-9077","propiedad","type-propiedad","status-publish","has-post-thumbnail","hentry","operacion-traspaso","poblacion-sagrada-familia","tipo-de-inmueble-traspaso-de-negocio","entry","has-media"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Traspaso de centro de bienestar junto a la Sagrada Familia - On Urbe<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/onurbegrup.com\/es\/propiedad\/traspaso-de-centro-de-bienestar-junto-a-la-sagrada-familia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Traspaso de centro de bienestar junto a la Sagrada Familia - On Urbe\" \/>\n<meta property=\"og:description\" content=\"Traspaso de centro de masajes\/spa-peluquer\u00eda-venta de productos completamente reformada y equipada lista para continuar con la actividad en barrio Sagrada Familia! El local cuenta con 90 m\u00b2 completamente reformado, el espacio cuenta con equipaciones de alta calidad, incluyendo jacuzzi, camillas profesionales, ducha y todo lo necesario para desarrollar el negocio sin necesidad de inversi\u00f3n adicional.&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/onurbegrup.com\/es\/propiedad\/traspaso-de-centro-de-bienestar-junto-a-la-sagrada-familia\/\" \/>\n<meta property=\"og:site_name\" content=\"On Urbe\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/onurbegrup.com\\\/es\\\/propiedad\\\/traspaso-de-centro-de-bienestar-junto-a-la-sagrada-familia\\\/\",\"url\":\"https:\\\/\\\/onurbegrup.com\\\/es\\\/propiedad\\\/traspaso-de-centro-de-bienestar-junto-a-la-sagrada-familia\\\/\",\"name\":\"Traspaso de centro de bienestar junto a la Sagrada Familia - On Urbe\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/onurbegrup.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/onurbegrup.com\\\/es\\\/propiedad\\\/traspaso-de-centro-de-bienestar-junto-a-la-sagrada-familia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/onurbegrup.com\\\/es\\\/propiedad\\\/traspaso-de-centro-de-bienestar-junto-a-la-sagrada-familia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/onurbegrup.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/traspaso-de-centro-de-bienestar-junto-a-la-sagrada-familia-001.webp\",\"datePublished\":\"2026-06-30T15:24:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/onurbegrup.com\\\/es\\\/propiedad\\\/traspaso-de-centro-de-bienestar-junto-a-la-sagrada-familia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/onurbegrup.com\\\/es\\\/propiedad\\\/traspaso-de-centro-de-bienestar-junto-a-la-sagrada-familia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/onurbegrup.com\\\/es\\\/propiedad\\\/traspaso-de-centro-de-bienestar-junto-a-la-sagrada-familia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/onurbegrup.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/traspaso-de-centro-de-bienestar-junto-a-la-sagrada-familia-001.webp\",\"contentUrl\":\"https:\\\/\\\/onurbegrup.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/traspaso-de-centro-de-bienestar-junto-a-la-sagrada-familia-001.webp\",\"width\":1600,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/onurbegrup.com\\\/es\\\/propiedad\\\/traspaso-de-centro-de-bienestar-junto-a-la-sagrada-familia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/onurbegrup.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Propiedades\",\"item\":\"https:\\\/\\\/onurbegrup.com\\\/propiedades\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Traspaso de centro de bienestar junto a la&hellip;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/onurbegrup.com\\\/#website\",\"url\":\"https:\\\/\\\/onurbegrup.com\\\/\",\"name\":\"On Urbe\",\"description\":\"Grup immobiliari\",\"publisher\":{\"@id\":\"https:\\\/\\\/onurbegrup.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/onurbegrup.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/onurbegrup.com\\\/#organization\",\"name\":\"On Urbe\",\"url\":\"https:\\\/\\\/onurbegrup.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/onurbegrup.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/onurbegrup.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/onurbegrup.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/logo.png\",\"width\":988,\"height\":241,\"caption\":\"On Urbe\"},\"image\":{\"@id\":\"https:\\\/\\\/onurbegrup.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Traspaso de centro de bienestar junto a la Sagrada Familia - On Urbe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/onurbegrup.com\/es\/propiedad\/traspaso-de-centro-de-bienestar-junto-a-la-sagrada-familia\/","og_locale":"es_ES","og_type":"article","og_title":"Traspaso de centro de bienestar junto a la Sagrada Familia - On Urbe","og_description":"Traspaso de centro de masajes\/spa-peluquer\u00eda-venta de productos completamente reformada y equipada lista para continuar con la actividad en barrio Sagrada Familia! El local cuenta con 90 m\u00b2 completamente reformado, el espacio cuenta con equipaciones de alta calidad, incluyendo jacuzzi, camillas profesionales, ducha y todo lo necesario para desarrollar el negocio sin necesidad de inversi\u00f3n adicional.&hellip;","og_url":"https:\/\/onurbegrup.com\/es\/propiedad\/traspaso-de-centro-de-bienestar-junto-a-la-sagrada-familia\/","og_site_name":"On Urbe","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/onurbegrup.com\/es\/propiedad\/traspaso-de-centro-de-bienestar-junto-a-la-sagrada-familia\/","url":"https:\/\/onurbegrup.com\/es\/propiedad\/traspaso-de-centro-de-bienestar-junto-a-la-sagrada-familia\/","name":"Traspaso de centro de bienestar junto a la Sagrada Familia - On Urbe","isPartOf":{"@id":"https:\/\/onurbegrup.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/onurbegrup.com\/es\/propiedad\/traspaso-de-centro-de-bienestar-junto-a-la-sagrada-familia\/#primaryimage"},"image":{"@id":"https:\/\/onurbegrup.com\/es\/propiedad\/traspaso-de-centro-de-bienestar-junto-a-la-sagrada-familia\/#primaryimage"},"thumbnailUrl":"https:\/\/onurbegrup.com\/wp-content\/uploads\/2026\/06\/traspaso-de-centro-de-bienestar-junto-a-la-sagrada-familia-001.webp","datePublished":"2026-06-30T15:24:49+00:00","breadcrumb":{"@id":"https:\/\/onurbegrup.com\/es\/propiedad\/traspaso-de-centro-de-bienestar-junto-a-la-sagrada-familia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/onurbegrup.com\/es\/propiedad\/traspaso-de-centro-de-bienestar-junto-a-la-sagrada-familia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/onurbegrup.com\/es\/propiedad\/traspaso-de-centro-de-bienestar-junto-a-la-sagrada-familia\/#primaryimage","url":"https:\/\/onurbegrup.com\/wp-content\/uploads\/2026\/06\/traspaso-de-centro-de-bienestar-junto-a-la-sagrada-familia-001.webp","contentUrl":"https:\/\/onurbegrup.com\/wp-content\/uploads\/2026\/06\/traspaso-de-centro-de-bienestar-junto-a-la-sagrada-familia-001.webp","width":1600,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/onurbegrup.com\/es\/propiedad\/traspaso-de-centro-de-bienestar-junto-a-la-sagrada-familia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/onurbegrup.com\/es\/"},{"@type":"ListItem","position":2,"name":"Propiedades","item":"https:\/\/onurbegrup.com\/propiedades\/"},{"@type":"ListItem","position":3,"name":"Traspaso de centro de bienestar junto a la&hellip;"}]},{"@type":"WebSite","@id":"https:\/\/onurbegrup.com\/#website","url":"https:\/\/onurbegrup.com\/","name":"On Urbe","description":"Grup immobiliari","publisher":{"@id":"https:\/\/onurbegrup.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/onurbegrup.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/onurbegrup.com\/#organization","name":"On Urbe","url":"https:\/\/onurbegrup.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/onurbegrup.com\/#\/schema\/logo\/image\/","url":"https:\/\/onurbegrup.com\/wp-content\/uploads\/2026\/06\/logo.png","contentUrl":"https:\/\/onurbegrup.com\/wp-content\/uploads\/2026\/06\/logo.png","width":988,"height":241,"caption":"On Urbe"},"image":{"@id":"https:\/\/onurbegrup.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/onurbegrup.com\/es\/wp-json\/wp\/v2\/propiedad\/9077","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/onurbegrup.com\/es\/wp-json\/wp\/v2\/propiedad"}],"about":[{"href":"https:\/\/onurbegrup.com\/es\/wp-json\/wp\/v2\/types\/propiedad"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/onurbegrup.com\/es\/wp-json\/wp\/v2\/media\/9078"}],"wp:attachment":[{"href":"https:\/\/onurbegrup.com\/es\/wp-json\/wp\/v2\/media?parent=9077"}],"wp:term":[{"taxonomy":"operacion","embeddable":true,"href":"https:\/\/onurbegrup.com\/es\/wp-json\/wp\/v2\/operacion?post=9077"},{"taxonomy":"poblacion","embeddable":true,"href":"https:\/\/onurbegrup.com\/es\/wp-json\/wp\/v2\/poblacion?post=9077"},{"taxonomy":"subzona","embeddable":true,"href":"https:\/\/onurbegrup.com\/es\/wp-json\/wp\/v2\/subzona?post=9077"},{"taxonomy":"tipo-de-inmueble","embeddable":true,"href":"https:\/\/onurbegrup.com\/es\/wp-json\/wp\/v2\/tipo-de-inmueble?post=9077"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/onurbegrup.com\/es\/wp-json\/wp\/v2\/zona?post=9077"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}